{"id":1398,"date":"2024-03-11T23:05:10","date_gmt":"2024-03-11T23:05:10","guid":{"rendered":"https:\/\/myriamferron.com\/?p=1398"},"modified":"2024-03-11T23:06:18","modified_gmt":"2024-03-11T23:06:18","slug":"la-reflexologie-faciale-contre-la-sinusite","status":"publish","type":"post","link":"https:\/\/myriamferron.com\/index.php\/2024\/03\/11\/la-reflexologie-faciale-contre-la-sinusite\/","title":{"rendered":"La r\u00e9flexologie faciale contre la sinusite"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/myriamferron.com\/wp-content\/uploads\/2024\/03\/moquette-et-sinus--1024x576.png\" alt=\"\" class=\"wp-image-1399\" srcset=\"https:\/\/myriamferron.com\/wp-content\/uploads\/2024\/03\/moquette-et-sinus--1024x576.png 1024w, https:\/\/myriamferron.com\/wp-content\/uploads\/2024\/03\/moquette-et-sinus--300x169.png 300w, https:\/\/myriamferron.com\/wp-content\/uploads\/2024\/03\/moquette-et-sinus--768x432.png 768w, https:\/\/myriamferron.com\/wp-content\/uploads\/2024\/03\/moquette-et-sinus--1536x864.png 1536w, https:\/\/myriamferron.com\/wp-content\/uploads\/2024\/03\/moquette-et-sinus--952x536.png 952w, https:\/\/myriamferron.com\/wp-content\/uploads\/2024\/03\/moquette-et-sinus--919x517.png 919w, https:\/\/myriamferron.com\/wp-content\/uploads\/2024\/03\/moquette-et-sinus--572x322.png 572w, https:\/\/myriamferron.com\/wp-content\/uploads\/2024\/03\/moquette-et-sinus-.png 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><br>En r\u00e9flexologie plantaire, La\u00a0<strong>zone r\u00e9flexe des sinus<\/strong>\u00a0est situ\u00e9 aux extr\u00e9mit\u00e9s des doigts de pieds. Je les stimule et tr\u00e8s souvent, vous sentez que vous respirez mieux par le nez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais quand je veux vraiment travailler sur votre sinusite, la <strong>r\u00e9flexologie faciale est plus efficace<\/strong>.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En exer\u00e7ant une pression sur des points pr\u00e9cis correspondant aux sinus frontaux, maxillaires et ethmo\u00efdaux (haut du nez), je peux\u00a0<strong>d\u00e9sengorger<\/strong>\u00a0vos sinus et ainsi faire\u00a0<strong>diminuer la douleur<\/strong> et vous procurer ainsi plus de confort. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.crenolibre.fr\/prendre-rdv\/14229_reflexologue-a-paris-12eme\" target=\"_blank\" rel=\"noreferrer noopener\">Prendre RDV en ligne<\/a>  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>En r\u00e9flexologie plantaire, La\u00a0zone r\u00e9flexe des sinus\u00a0est situ\u00e9 aux extr\u00e9mit\u00e9s des doigts de pieds. Je les stimule et tr\u00e8s souvent, vous sentez que vous respirez mieux par le nez. Mais quand je veux vraiment travailler sur votre sinusite, la r\u00e9flexologie faciale est plus efficace.\u00a0 En exer\u00e7ant une pression sur des points pr\u00e9cis correspondant aux sinus [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1398","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/myriamferron.com\/index.php\/wp-json\/wp\/v2\/posts\/1398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/myriamferron.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/myriamferron.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/myriamferron.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/myriamferron.com\/index.php\/wp-json\/wp\/v2\/comments?post=1398"}],"version-history":[{"count":2,"href":"https:\/\/myriamferron.com\/index.php\/wp-json\/wp\/v2\/posts\/1398\/revisions"}],"predecessor-version":[{"id":1401,"href":"https:\/\/myriamferron.com\/index.php\/wp-json\/wp\/v2\/posts\/1398\/revisions\/1401"}],"wp:attachment":[{"href":"https:\/\/myriamferron.com\/index.php\/wp-json\/wp\/v2\/media?parent=1398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/myriamferron.com\/index.php\/wp-json\/wp\/v2\/categories?post=1398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/myriamferron.com\/index.php\/wp-json\/wp\/v2\/tags?post=1398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}